{"id":4378,"date":"2016-10-20T12:00:26","date_gmt":"2016-10-20T10:00:26","guid":{"rendered":"https:\/\/oldtimer-veranstaltung.de\/service\/?p=4378"},"modified":"2016-10-20T18:26:16","modified_gmt":"2016-10-20T16:26:16","slug":"autolacke-und-farben-im-letzten-jahrhundert","status":"publish","type":"post","link":"https:\/\/oldtimer-veranstaltung.de\/service\/autolacke-und-farben-im-letzten-jahrhundert\/","title":{"rendered":"Autolacke und Farben im letzten Jahrhundert"},"content":{"rendered":"<p>\u00dcberall ist bekannt, dass Henry Ford am Anfang des 20. Jahrhunderts f\u00fcr seine T-Modelle die Einheitsfarbe Schwarz favorisierte. Doch bis heute haben sich die technischen Gegebenheiten der Lacktechnik, Farbenvielfalt und Trendfarben im Zeitablauf erheblich ge\u00e4ndert.<\/p>\n<p>Schon damals gab, sofern technisch machbar, der pers\u00f6nliche Geschmack den Ausschlag f\u00fcr die Wagenfarbe. Fr\u00fche Motorkutschen wurden in der Regel in Dunkelbraun, Dunkelgr\u00fcn oder Dunkelblau geliefert. Diese Farben waren ein Verm\u00e4chtnis der Pferdekutschen, die gew\u00f6hnlich gedeckte Farbt\u00f6ne trugen. Kaiser Wilhelm II. lie\u00df sich gern in grauen Autos spazieren fahren, analog der Farbgebung seiner Kriegsmarine. Zur damaligen Zeit verdreckten helle Lackierungen sehr schnell und waren wenig sinnvoll bei den in der Regel noch unbefestigten Stra\u00dfen jener Tage.<\/p>\n<h3>Henry Ford verwendete Schellack<\/h3>\n<p>Der Grund f\u00fcr die damalige Einheitsfarbe von Ford beim <a href=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/ford-t-blechliesel-mit-20-ps\/\" title=\"Link zum Beitrag \u00fcber das Ford T-Modell\" target=\"_blank\">T-Modell<\/a> war der Stand der Substanzen der Farbe und die Lackiertechnik Anfang des 20. Jahrhunderts. Die \u00d6lfarbe wurde mit dem Pinsel aufgetragen. Die Deckschicht enthielt Ru\u00dfpigmente zur Farbgebung, was helle Farben fast unm\u00f6glich machte und noch dazu sehr teuer war. Der Trocknungsprozess der \u00d6lfarbe dauerte f\u00fcnf bis acht Wochen. Ford nutzte als einer der ersten Fabrikanten sogenannten Schellack aus Ostasien, der d\u00fcnnfl\u00fcssiger war und wesentlich schneller trocknete.<\/p>\n<h3>Autolack der 30er-, 40er- und 50er-Jahre<\/h3>\n<p>In den 30er Jahren kamen erstmals deckende wei\u00dfe Lacke auf den <a title=\"Markt\" class=\"aalmanual\" href=\"https:\/\/oldtimer-veranstaltung.de\/service\/anzeigen\/anzeigen-durchsuchen\/\">Markt<\/a>. Schwarz abgesetzte Kotfl\u00fcgel galten als Modetrend. Neu waren damals Kunstharzlacke. In den Kriegsjahren war Olivgr\u00fcn schlicht die Einheitsfarbe.<\/p>\n<figure id=\"attachment_4384\" aria-describedby=\"caption-attachment-4384\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Ford-30er-Jahre.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Ford-30er-Jahre.jpg\" alt=\"Ford 30er-Jahre\" width=\"730\" height=\"544\" class=\"size-full wp-image-4384\" srcset=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Ford-30er-Jahre.jpg 730w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Ford-30er-Jahre-300x223.jpg 300w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Ford-30er-Jahre-125x93.jpg 125w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Ford-30er-Jahre-50x37.jpg 50w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><figcaption id=\"caption-attachment-4384\" class=\"wp-caption-text\">Ford 30er-Jahre<\/figcaption><\/figure>\n<p>In den 50er Jahren wurden dann mit weiteren technischen M\u00f6glichkeiten auch hellere und mehr Farbt\u00f6ne angeboten. Ende der 50er Jahre lagen zwei- oder gar Dreifarblackierungen im Trend. Geranienrot und pastellwei\u00dfe Barock-Taunus oder Borgward Isabella Coup\u00e9s in Elfenbein, kombiniert mit Himmelblau, pr\u00e4gten das Stra\u00dfenbild. Erinnert werden soll auch an die Export-K\u00e4fer in Capriblau.<\/p>\n<figure id=\"attachment_4380\" aria-describedby=\"caption-attachment-4380\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Borgward-Isabella_zweifarbig.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Borgward-Isabella_zweifarbig.jpg\" alt=\"Borgward Isabella Coup\u00e9 zweifarbig\" width=\"730\" height=\"413\" class=\"size-full wp-image-4380\" srcset=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Borgward-Isabella_zweifarbig.jpg 730w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Borgward-Isabella_zweifarbig-300x169.jpg 300w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Borgward-Isabella_zweifarbig-125x70.jpg 125w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Borgward-Isabella_zweifarbig-50x28.jpg 50w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><figcaption id=\"caption-attachment-4380\" class=\"wp-caption-text\">Borgward Isabella Coup\u00e9 zweifarbig<\/figcaption><\/figure>\n<h3>Knallbunte Lackfarben der 60er- und 70er-Jahre<\/h3>\n<p>Ende der 60er-Jahre wurde es bunter auf den Stra\u00dfen. Helle Farben lagen im Trend, denn sie waren auch bei schlechter Sicht besser zu sehen und grelle Kontrastfarben wurden ein Merkmal der Sicherheit. Doch die 70er-Jahre wurden noch bunter. Die Mode setzte den Trend und die Menschen kauften Autos in <a href=\"https:\/\/oldtimer-veranstaltung.de\/2011\/04\/freude-am-fahren-mit-bmw-02\/\" title=\"Link zu den bunten Farben der 70er Jahre\" target=\"_blank\">Inkaorange<\/a>, <a href=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/bmw-02-mit-preissteigerungen\/\" title=\"Link zum BMW 02 in Golfgelb\" target=\"_blank\">Golfgelb<\/a>, <a href=\"https:\/\/oldtimer-veranstaltung.de\/2010\/03\/golf-1-gti\/\" title=\"Link zum Golf 1 in Marsrot\" target=\"_blank\">Marsrot<\/a>, &#8230; Die Lackchemie machte es m\u00f6glich. Seit den 70er-Jahren setzten sich die Zweikomponenten-Acryllacke allgemein durch.<\/p>\n<figure id=\"attachment_4382\" aria-describedby=\"caption-attachment-4382\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Volkswagen-Kaefer-1303.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Volkswagen-Kaefer-1303.jpg\" alt=\"Volkswagen K\u00e4fer 1303\" width=\"730\" height=\"490\" class=\"size-full wp-image-4382\" srcset=\"https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Volkswagen-Kaefer-1303.jpg 730w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Volkswagen-Kaefer-1303-300x201.jpg 300w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Volkswagen-Kaefer-1303-125x83.jpg 125w, https:\/\/oldtimer-veranstaltung.de\/service\/wp-content\/uploads\/2014\/09\/Volkswagen-Kaefer-1303-50x33.jpg 50w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><figcaption id=\"caption-attachment-4382\" class=\"wp-caption-text\">Volkswagen K\u00e4fer 1303<\/figcaption><\/figure>\n<h3>Lackfarben der 80er- und 90er-Jahre<\/h3>\n<p>Doch dann war der Farbrausch mit der Verschrottung der Vorg\u00e4ngermodelle, die vom Rost zernagt waren, zu Ende. Die Farben der Autos wurden in den 80er- und 90er-Jahren weniger grell. Das Auto war damals Umweltverschmutzer. Mitte der 80er Jahre kamen die ersten Katalysatoren zur Schadstoffverminderung ab Fabrik in den Fahrzeugen zum Einbau. Der Kalte Krieg war damals k\u00e4lter als zu Beginn der 80er Jahre. Der Modetrend ging hin zu strengen, dunklen Farbt\u00f6nen, die zwischen Rauchsilber und Tiefdunkelgrau lagen. Diese einfallslosen Farben mit einem hohen Anteil Schwarz folgten fast 20 Jahre. Durch das Retrodesign in der Automobilhersteller wird es langsam wieder bunter auf den Stra\u00dfen und Parkpl\u00e4tzen. Gr\u00fcn- und Braunt\u00f6ne waren immer Au\u00dfenseiter der Farbpaletten der Hersteller.<\/p>\n<h3>Lackfarben in der Neuzeit<\/h3>\n<p>Nach Jahren der Verbannung von Wei\u00df bei der Autoindustrie ist die Farbe f\u00fcr Dienstwagen wieder sehr beliebt und belebt das Gesch\u00e4ft der Wagenwaschanlagen bei dem wieder schlechteren Zustand der Stra\u00dfen. Heute werden ab Werk Lacke auf Wasserbasis als Industrie-Standard genutzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcberall ist bekannt, dass Henry Ford am Anfang des 20. Jahrhunderts f\u00fcr seine T-Modelle die Einheitsfarbe Schwarz favorisierte. Doch bis heute haben sich die technischen Gegebenheiten der Lacktechnik, Farbenvielfalt und&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[341,131,164,405,342,343],"tags":[409],"class_list":["post-4378","post","type-post","status-publish","format-standard","hentry","category-ancestor","category-oldtimer","category-oldtimer-wissen","category-technologie","category-veteran","category-vintage","tag-farben-und-lacke"],"_links":{"self":[{"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/posts\/4378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/comments?post=4378"}],"version-history":[{"count":0,"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/posts\/4378\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/media?parent=4378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/categories?post=4378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldtimer-veranstaltung.de\/service\/wp-json\/wp\/v2\/tags?post=4378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}