{"id":5857,"date":"2016-05-16T12:43:14","date_gmt":"2016-05-16T10:43:14","guid":{"rendered":"https:\/\/oldtimer-veranstaltung.de\/inserat\/?p=5857"},"modified":"2016-05-16T12:43:14","modified_gmt":"2016-05-16T10:43:14","slug":"brotauslieferung-mit-elektroantrieb","status":"publish","type":"post","link":"https:\/\/oldtimer-veranstaltung.de\/inserat\/brotauslieferung-mit-elektroantrieb\/","title":{"rendered":"Brotauslieferung mit Elektroantrieb"},"content":{"rendered":"<p>Das Wittler-Brotauto aus dem Bestand der Stiftung Deutsches Technikmuseum Berlin ist ein Nischenprodukt. Benzin und Diesel waren in den Kriegsjahren streng rationiert und so setzte die Maschinenfabrik Esslingen im Jahr 1943 auf Elektroantrieb. Die Antriebstechnik erwies sich als robust und in der Bedienung als zuverl\u00e4ssig.<\/p>\n<figure id=\"attachment_5864\" aria-describedby=\"caption-attachment-5864\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2417.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2417.jpg\" alt=\"Wittler-Brot Lastwagen 1943\" width=\"730\" height=\"548\" class=\"size-full wp-image-5864\" srcset=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2417.jpg 730w, https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2417-300x225.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><figcaption id=\"caption-attachment-5864\" class=\"wp-caption-text\">Wittler-Brot Lastwagen 1943<\/figcaption><\/figure>\n<h3>Wittler B\u00e4ckerei<\/h3>\n<p>Zur Belieferung der Verkaufsstellen unterhielt die damalige Berliner Gro\u00dfb\u00e4ckerei Wittler einen eigenen Fuhrpark. Durch die typische rot-braune Gestaltung der Fahrzeuge fielen die Wittler-Brot-Lieferwagen im Stadtgebiet von Berlin immer auf. Die Eletromobile ersetzten bei dem Unternehmen die Pferdegespanne. <\/p>\n<figure id=\"attachment_5865\" aria-describedby=\"caption-attachment-5865\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2418.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2418.jpg\" alt=\"Wittler-Brot Lastwagen Elektroantrieb\" width=\"730\" height=\"548\" class=\"size-full wp-image-5865\" srcset=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2418.jpg 730w, https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2418-300x225.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><figcaption id=\"caption-attachment-5865\" class=\"wp-caption-text\">Wittler-Brot Lastwagen Elektroantrieb<\/figcaption><\/figure>\n<p>Wittler-Brot wurde 1898 in der Maxstra\u00dfe in Wedding gegr\u00fcndet. In der Zeit nach dem Ersten Weltkrieg war das Unternehmen der gr\u00f6\u00dfte Brotproduzent in Europa mit 2.000 Angestellten. Das Ende kam 1982 mit dem Konkurs. <\/p>\n<figure id=\"attachment_5866\" aria-describedby=\"caption-attachment-5866\" style=\"width: 730px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2420.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2420.jpg\" alt=\"Wittler-Brot Lastwagen Fahrerhaus\" width=\"730\" height=\"548\" class=\"size-full wp-image-5866\" srcset=\"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2420.jpg 730w, https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-content\/uploads\/2016\/05\/Wittler-Brot-B_2420-300x225.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><figcaption id=\"caption-attachment-5866\" class=\"wp-caption-text\">Wittler-Brot Lastwagen Fahrerhaus<\/figcaption><\/figure>\n<h3>Technische Daten<\/h3>\n<p>Der Strom wurde in Bleiakkus gespeichert, ein Reihenschlussmotor wandelte die Energie in Bewegung um. Problematisch war das hohe Gewicht der Batterien und die begrenzte Reichweite. Die Batterien wurden \u00fcber Nacht in 5 &#8211; 6 Stunden f\u00fcr den n\u00e4chsten Tag aufgeladen. Eingesetzt wurde der Lastwagen in einer Flotte von 10 Lieferwagen bis weit in die 70er Jahre des letzten Jahrhunderts. Nur zwei Exemplare sind erhalten geblieben.<\/p>\n<p>Leistung: 11 PS, Bremsen: Vierrad-Servo-Bremse &#8222;System Perrot&#8220;, H\u00f6chstgeschwindigkeit 28 km\/h, Antrieb auf die Hinterr\u00e4der, Fahrbereich etwa 60 km.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Wittler-Brotauto aus dem Bestand der Stiftung Deutsches Technikmuseum Berlin ist ein Nischenprodukt. Benzin und Diesel waren in den Kriegsjahren streng rationiert und so setzte die Maschinenfabrik Esslingen im Jahr&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568,34],"tags":[569,40,525],"class_list":["post-5857","post","type-post","status-publish","format-standard","hentry","category-maschinenfabrik-esslingen","category-oldtimer-schaufenster","tag-elektroantrieb","tag-museum","tag-technik"],"_links":{"self":[{"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/posts\/5857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/comments?post=5857"}],"version-history":[{"count":0,"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/posts\/5857\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/media?parent=5857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/categories?post=5857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldtimer-veranstaltung.de\/inserat\/wp-json\/wp\/v2\/tags?post=5857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}